{"id":69673,"date":"2025-03-07T18:13:46","date_gmt":"2025-03-07T16:13:46","guid":{"rendered":"https:\/\/www.italtel.com\/celebrating-womens-voices-a-global-tribute-for-international-womens-day\/"},"modified":"2025-03-07T18:25:30","modified_gmt":"2025-03-07T16:25:30","slug":"celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer","status":"publish","type":"post","link":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/","title":{"rendered":"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer"},"content":{"rendered":"\n<div class=\"row\"  id=\"row-1288829471\">\n\n\n\t<div id=\"col-2046726125\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1639792621\" class=\"text fontsize_18 color_black\">\n\t\t\n\n<p data-start=\"2336\" data-end=\"2645\">En Italtel, la diversidad no es solo un valor en el que creemos, sino una fuerza que nos impulsa a avanzar. Para conmemorar el <strong data-start=\"2463\" data-end=\"2496\">D\u00eda Internacional de la Mujer<\/strong>, pedimos a nuestros colegas de Italia, Espa\u00f1a, Alemania, Per\u00fa, Colombia y Brasil que compartieran sus pensamientos sobre lo que significa ser mujer.<\/p>\n<p data-start=\"2647\" data-end=\"2898\">El resultado es un emotivo video que recoge las perspectivas, emociones y experiencias \u00fanicas de las mujeres que todos los d\u00edas contribuyen al futuro de Italtel. Sus voces reflejan la pasi\u00f3n, el talento y la determinaci\u00f3n que nos definen como empresa.<\/p>\n<p data-start=\"2900\" data-end=\"3146\">Creemos que la diversidad fortalece nuestra comunidad, y estamos orgullosos de dar espacio a las historias y voces de nuestra gente. Mira el video y escucha directamente a nuestros compa\u00f1eros compartir sus reflexiones sobre el poder de ser mujer.<\/p>\n<p data-start=\"3148\" data-end=\"3195\"><strong data-start=\"3151\" data-end=\"3195\">Mira el video ahora y escucha sus voces.<\/strong><\/p>\n\t\t\t<\/div>\n\t\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><iframe loading=\"lazy\" title=\"Our voices for March 8th\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/yO_hpgLxTpY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2046726125 > .col-inner {\n  padding: 6rem 11rem 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-445215250\" class=\"col sibebar_col medium-3 small-12 large-3\"  >\n\t\t<div class=\"is-sticky-column\"><div class=\"is-sticky-column__inner\">\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1684240569\" class=\"text fontsize_16 color_black fontweight_500\">\n\t\t\n\nTECH KEYWORDS\n\t\t\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:2rem;margin-bottom:2rem;max-width:100%;height:1px;background-color:rgba(112, 112, 112, 0.302);\"><\/div>\n\n\t<div id=\"text-404418308\" class=\"text fontsize_18 color_black\">\n\t\t\n\n<p>INTERNATIONAL WOMEN&#8217;S DAY<\/p>\n\t\t\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:2rem;margin-bottom:2rem;max-width:100%;height:1px;background-color:rgba(112, 112, 112, 0.302);\"><\/div>\n\n\t<div id=\"text-3288848524\" class=\"text fontsize_18 color_black\">\n\t\t\n\n<p>VOICES OF WOMEN<\/p>\n\t\t\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:2rem;margin-bottom:2rem;max-width:100%;height:1px;background-color:rgba(112, 112, 112, 0.302);\"><\/div>\n\n\t<div id=\"text-1361928432\" class=\"text fontsize_18 color_black\">\n\t\t\n\n<p>GENDER PARITY<\/p>\n\t\t\t<\/div>\n\t\n\t<div id=\"gap-651304186\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-651304186 {\n  padding-top: 13rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3502520063\" class=\"text fontsize_16 color_black fontweight_500\">\n\t\t\n\nSHARE THE PAGE\n\t\t\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:2rem;margin-bottom:2rem;max-width:100%;height:1px;background-color:rgba(112, 112, 112, 0.302);\"><\/div>\n\n\t<div class=\"img has-hover socialshare_icon linkedin x md-x lg-x y md-y lg-y\" id=\"image_458268975\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/09\/Linkedin-icon.svg\" class=\"attachment-large size-large\" alt=\"Linkedin-icon\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_458268975 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover socialshare_icon instagram x md-x lg-x y md-y lg-y\" id=\"image_1809717349\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"27\" height=\"27\" src=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/07\/Raggruppa-12942.png\" class=\"attachment-large size-large\" alt=\"Instagram icon\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1809717349 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover socialshare_icon ex x md-x lg-x y md-y lg-y\" id=\"image_1235559636\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/09\/X-icon.svg\" class=\"attachment-large size-large\" alt=\"X-icon\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1235559636 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\n<style>\n#col-445215250 > .is-sticky-column > .is-sticky-column__inner > .col-inner {\n  padding: 6rem 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":69662,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1004],"tags":[969,1028],"class_list":["post-69673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-es-pe","tag-company-es-pe","tag-women-in-tech-es-pe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer - Italtel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer - Italtel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/\" \/>\n<meta property=\"og:site_name\" content=\"Italtel\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T16:13:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T16:25:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png\" \/>\n\t<meta property=\"og:image:width\" content=\"755\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniela Fontana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Italtel\" \/>\n<meta name=\"twitter:site\" content=\"@Italtel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela Fontana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/\"},\"author\":{\"name\":\"Daniela Fontana\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/person\\\/38f315d5a978255f0cf320055bad5afe\"},\"headline\":\"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer\",\"datePublished\":\"2025-03-07T16:13:46+00:00\",\"dateModified\":\"2025-03-07T16:25:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vieo-International-Women-Day-Italtel.png\",\"keywords\":[\"Company\",\"Women in Tech\"],\"articleSection\":[\"News\"],\"inLanguage\":\"es-Pe\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/\",\"name\":\"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer - Italtel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vieo-International-Women-Day-Italtel.png\",\"datePublished\":\"2025-03-07T16:13:46+00:00\",\"dateModified\":\"2025-03-07T16:25:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/#breadcrumb\"},\"inLanguage\":\"es-Pe\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-Pe\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vieo-International-Women-Day-Italtel.png\",\"contentUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vieo-International-Women-Day-Italtel.png\",\"width\":755,\"height\":388,\"caption\":\"Vieo International Women Day Italtel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/es-pe\\\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\",\"name\":\"Italtel\",\"description\":\"Italtel Group&#039;s company website\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-Pe\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\",\"name\":\"Italtel S.p.A.\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-Pe\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Italtel_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Italtel_logo.png\",\"width\":591,\"height\":139,\"caption\":\"Italtel S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Italtel\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/italtel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/italtel_hq\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/person\\\/38f315d5a978255f0cf320055bad5afe\",\"name\":\"Daniela Fontana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-Pe\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"caption\":\"Daniela Fontana\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer - Italtel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/","og_locale":"es_ES","og_type":"article","og_title":"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer - Italtel","og_url":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/","og_site_name":"Italtel","article_published_time":"2025-03-07T16:13:46+00:00","article_modified_time":"2025-03-07T16:25:30+00:00","og_image":[{"width":755,"height":388,"url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","type":"image\/png"}],"author":"Daniela Fontana","twitter_card":"summary_large_image","twitter_creator":"@Italtel","twitter_site":"@Italtel","twitter_misc":{"Written by":"Daniela Fontana","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/#article","isPartOf":{"@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/"},"author":{"name":"Daniela Fontana","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/person\/38f315d5a978255f0cf320055bad5afe"},"headline":"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer","datePublished":"2025-03-07T16:13:46+00:00","dateModified":"2025-03-07T16:25:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/"},"wordCount":320,"publisher":{"@id":"https:\/\/www.italtel.com\/de\/#organization"},"image":{"@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","keywords":["Company","Women in Tech"],"articleSection":["News"],"inLanguage":"es-Pe"},{"@type":"WebPage","@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/","url":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/","name":"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer - Italtel","isPartOf":{"@id":"https:\/\/www.italtel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/#primaryimage"},"image":{"@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","datePublished":"2025-03-07T16:13:46+00:00","dateModified":"2025-03-07T16:25:30+00:00","breadcrumb":{"@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/#breadcrumb"},"inLanguage":"es-Pe","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/"]}]},{"@type":"ImageObject","inLanguage":"es-Pe","@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/#primaryimage","url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","contentUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","width":755,"height":388,"caption":"Vieo International Women Day Italtel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italtel.com\/es-pe\/celebrando-las-voces-de-las-mujeres-un-tributo-global-por-el-dia-internacional-de-la-mujer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italtel.com\/de\/"},{"@type":"ListItem","position":2,"name":"Celebrando las voces de las mujeres: un tributo global por el D\u00eda Internacional de la Mujer"}]},{"@type":"WebSite","@id":"https:\/\/www.italtel.com\/de\/#website","url":"https:\/\/www.italtel.com\/de\/","name":"Italtel","description":"Italtel Group&#039;s company website","publisher":{"@id":"https:\/\/www.italtel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italtel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-Pe"},{"@type":"Organization","@id":"https:\/\/www.italtel.com\/de\/#organization","name":"Italtel S.p.A.","url":"https:\/\/www.italtel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"es-Pe","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/11\/Italtel_logo.png","contentUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/11\/Italtel_logo.png","width":591,"height":139,"caption":"Italtel S.p.A."},"image":{"@id":"https:\/\/www.italtel.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Italtel","https:\/\/www.linkedin.com\/company\/italtel\/","https:\/\/www.instagram.com\/italtel_hq\/"]},{"@type":"Person","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/person\/38f315d5a978255f0cf320055bad5afe","name":"Daniela Fontana","image":{"@type":"ImageObject","inLanguage":"es-Pe","@id":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","caption":"Daniela Fontana"}}]}},"_links":{"self":[{"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/posts\/69673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/comments?post=69673"}],"version-history":[{"count":2,"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/posts\/69673\/revisions"}],"predecessor-version":[{"id":69675,"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/posts\/69673\/revisions\/69675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/media\/69662"}],"wp:attachment":[{"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/media?parent=69673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/categories?post=69673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italtel.com\/es-pe\/wp-json\/wp\/v2\/tags?post=69673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}