{"id":55011,"date":"2019-03-20T15:53:54","date_gmt":"2019-03-20T13:53:54","guid":{"rendered":"https:\/\/www.italtel.com\/crescita-attraverso-le-sinergie\/"},"modified":"2024-08-09T12:25:18","modified_gmt":"2024-08-09T10:25:18","slug":"crescita-attraverso-le-sinergie","status":"publish","type":"post","link":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/","title":{"rendered":"Crescita attraverso le sinergie"},"content":{"rendered":"<h5><strong>I risultati del gruppo Exprivia | Italtel alla Star Conference di Borsa Italiana<\/strong><\/h5>\n<ul>\n<li>In aumento fatturato e margini nel primo bilancio consolidato del gruppo Exprivia|Italtel<\/li>\n<li>Stefano Pileri cooptato nel CdA di Exprivia<\/li>\n<\/ul>\n<p><strong>20 marzo 2019 \u2013<\/strong> I dati economici positivi del processo di integrazione fra Exprivia &#8211; societ\u00e0 quotata al segmento STAR di Borsa Italiana [XPR.MI] &#8211; e Italtel sono stati illustrati a investitori e analisti, nell\u2019ambito della Star Conference di Borsa Italiana, dal presidente e amministratore delegato di Exprivia, Domenico Favuzzi, e dall\u2019amministratore delegato di Italtel, Stefano Pileri, nuovo membro del CdA di Exprivia. Il 2018 \u00e8 stato il primo anno dell\u2019ingresso di Italtel nel perimetro di consolidamento, e il primo bilancio del gruppo presenta, dal punto di vista contabile, ricavi e margini in crescita, ma soprattutto registra riscontro e consenso dal mercato grazie a progetti sviluppati e proposti in completa sinergia da Exprivia e Italtel.<\/p>\n<p>Sono stati illustrati i risultati conseguiti nel 2018, con ricavi di gruppo di oltre 623 milioni, superiori ai 614 milioni pro-forma dell\u2019anno precedente, un Ebitda di circa 42 milioni, quasi raddoppiato rispetto al 2017, e il miglioramento della posizione finanziaria netta scesa a -214,6 milioni. Fra le unit\u00e0 produttive spicca il comparto Industry con una crescita del 10%, seguito dalla Sanit\u00e0 e dalla Pubblica Amministrazione. In linea con le previsioni l\u2019attivit\u00e0 nel comparto della Finanza e Assicurazioni e in quello Telco &amp; Media.<\/p>\n<p>Tra i successi prodotti dalla sinergia di Exprivia e Italtel, sono stati illustrati progetti e soluzioni messi in cantiere nel 2018. In particolare, nell\u2019ambito di Industria 4.0, la soluzione Indy SUITE per la connessione degli impianti con le tecnologie wired e wireless e l\u2019integrazione con sistemi gestionali; nella Sanit\u00e0, di rilievo la realizzazione in Messico della pi\u00f9 grande rete di informazioni cliniche e diagnostiche per conto dell\u2019ente mutualistico dei dipendenti pubblici. Per il Corpo Nazionale dei Vigili del Fuoco, il potenziamento del sistema di prevenzione e gestione dei rischi ambientali di origine chimica, biologica, nucleare, ecc. Nel settore Telco, con Open Fiber lo sviluppo della rete a banda ultralarga per le aree bianche del Paese.<\/p>\n<p>\u00c8 stata ribadita la visione del futuro del gruppo, di recente presentata a fine febbraio al Mobile World Congress di Barcellona, uno dei pi\u00f9 importanti appuntamenti mondiali dell\u2019ICT.<\/p>\n<p>\u201cL\u2019andamento soddisfacente dei conti economici del 2018 \u2013 ha affermato Domenico Favuzzi &#8211; sono una evidente conferma della validit\u00e0 del piano di integrazione fra Exprivia e Italtel, a cui hanno contribuito i successi industriali dei progetti concepiti e sviluppati insieme dalle due aziende. In questo quadro di continuo progresso nell\u2019integrazione in un unico gruppo, si inserisce anche l\u2019ingresso per cooptazione dell\u2019amministratore delegato di Italtel Stefano Pileri nel nuovo CdA di Exprivia, il cui contributo riteniamo essenziale per continuare la costruzione di uno dei pi\u00f9 grandi player del settore tecnologico a livello nazionale e internazionale\u201d.<\/p>\n<p>\u201cIl primo anno di consolidamento di Italtel all\u2019interno del gruppo costituito con Exprivia \u2013 ha sottolineato Stefano Pileri &#8211; ci trova soddisfatti per il contributo fornito, sia in termini di ricavi che per l\u2019operativit\u00e0 comune sviluppata in progetti e soluzioni in Italia e all\u2019estero. Presentarsi come interlocutore unico, in grado di seguire anche i progetti pi\u00f9 complessi lungo l\u2019intero ciclo di vita, dimostra la capacit\u00e0 di fare sinergia e di andare sul mercato con strumenti e competenze adatte a anticipare l\u2019innovazione tecnologica nell\u2019ICT e a soddisfare la domanda di trasformazione digitale\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I risultati del gruppo Exprivia | Italtel alla Star Conference di Borsa Italiana In aumento fatturato e margini nel primo bilancio consolidato del gruppo Exprivia|Italtel Stefano Pileri cooptato nel CdA&nbsp;&#8230;<\/p>\n","protected":false},"author":6,"featured_media":48508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[732],"tags":[],"class_list":["post-55011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicato-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crescita attraverso le sinergie - Italtel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crescita attraverso le sinergie - Italtel\" \/>\n<meta property=\"og:description\" content=\"I risultati del gruppo Exprivia | Italtel alla Star Conference di Borsa Italiana In aumento fatturato e margini nel primo bilancio consolidato del gruppo Exprivia|Italtel Stefano Pileri cooptato nel CdA&nbsp;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/\" \/>\n<meta property=\"og:site_name\" content=\"Italtel\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-20T13:53:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-09T10:25:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CORPORATE_SedeExprivia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela Fontana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Italtel\" \/>\n<meta name=\"twitter:site\" content=\"@Italtel\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela Fontana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/\"},\"author\":{\"name\":\"Daniela Fontana\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/person\\\/38f315d5a978255f0cf320055bad5afe\"},\"headline\":\"Crescita attraverso le sinergie\",\"datePublished\":\"2019-03-20T13:53:54+00:00\",\"dateModified\":\"2024-08-09T10:25:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/\"},\"wordCount\":565,\"publisher\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/CORPORATE_SedeExprivia.jpg\",\"articleSection\":[\"Comunicato stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/\",\"name\":\"Crescita attraverso le sinergie - Italtel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/CORPORATE_SedeExprivia.jpg\",\"datePublished\":\"2019-03-20T13:53:54+00:00\",\"dateModified\":\"2024-08-09T10:25:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/CORPORATE_SedeExprivia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/CORPORATE_SedeExprivia.jpg\",\"width\":1440,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/crescita-attraverso-le-sinergie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crescita attraverso le sinergie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\",\"name\":\"Italtel\",\"description\":\"Italtel Group&#039;s company website\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\",\"name\":\"Italtel S.p.A.\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Italtel_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Italtel_logo.png\",\"width\":591,\"height\":139,\"caption\":\"Italtel S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Italtel\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/italtel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/italtel_hq\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/person\\\/38f315d5a978255f0cf320055bad5afe\",\"name\":\"Daniela Fontana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"caption\":\"Daniela Fontana\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crescita attraverso le sinergie - Italtel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/","og_locale":"it_IT","og_type":"article","og_title":"Crescita attraverso le sinergie - Italtel","og_description":"I risultati del gruppo Exprivia | Italtel alla Star Conference di Borsa Italiana In aumento fatturato e margini nel primo bilancio consolidato del gruppo Exprivia|Italtel Stefano Pileri cooptato nel CdA&nbsp;...","og_url":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/","og_site_name":"Italtel","article_published_time":"2019-03-20T13:53:54+00:00","article_modified_time":"2024-08-09T10:25:18+00:00","og_image":[{"width":1440,"height":600,"url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CORPORATE_SedeExprivia.jpg","type":"image\/jpeg"}],"author":"Daniela Fontana","twitter_card":"summary_large_image","twitter_creator":"@Italtel","twitter_site":"@Italtel","twitter_misc":{"Scritto da":"Daniela Fontana","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/#article","isPartOf":{"@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/"},"author":{"name":"Daniela Fontana","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/person\/38f315d5a978255f0cf320055bad5afe"},"headline":"Crescita attraverso le sinergie","datePublished":"2019-03-20T13:53:54+00:00","dateModified":"2024-08-09T10:25:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/"},"wordCount":565,"publisher":{"@id":"https:\/\/www.italtel.com\/de\/#organization"},"image":{"@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CORPORATE_SedeExprivia.jpg","articleSection":["Comunicato stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/","url":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/","name":"Crescita attraverso le sinergie - Italtel","isPartOf":{"@id":"https:\/\/www.italtel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/#primaryimage"},"image":{"@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CORPORATE_SedeExprivia.jpg","datePublished":"2019-03-20T13:53:54+00:00","dateModified":"2024-08-09T10:25:18+00:00","breadcrumb":{"@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/#primaryimage","url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CORPORATE_SedeExprivia.jpg","contentUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CORPORATE_SedeExprivia.jpg","width":1440,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.italtel.com\/it\/crescita-attraverso-le-sinergie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italtel.com\/it\/"},{"@type":"ListItem","position":2,"name":"Crescita attraverso le sinergie"}]},{"@type":"WebSite","@id":"https:\/\/www.italtel.com\/de\/#website","url":"https:\/\/www.italtel.com\/de\/","name":"Italtel","description":"Italtel Group&#039;s company website","publisher":{"@id":"https:\/\/www.italtel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italtel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.italtel.com\/de\/#organization","name":"Italtel S.p.A.","url":"https:\/\/www.italtel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/11\/Italtel_logo.png","contentUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/11\/Italtel_logo.png","width":591,"height":139,"caption":"Italtel S.p.A."},"image":{"@id":"https:\/\/www.italtel.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Italtel","https:\/\/www.linkedin.com\/company\/italtel\/","https:\/\/www.instagram.com\/italtel_hq\/"]},{"@type":"Person","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/person\/38f315d5a978255f0cf320055bad5afe","name":"Daniela Fontana","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","caption":"Daniela Fontana"}}]}},"_links":{"self":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts\/55011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/comments?post=55011"}],"version-history":[{"count":1,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts\/55011\/revisions"}],"predecessor-version":[{"id":57040,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts\/55011\/revisions\/57040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/media\/48508"}],"wp:attachment":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/media?parent=55011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/categories?post=55011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/tags?post=55011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}