{"id":55324,"date":"2016-11-18T11:25:14","date_gmt":"2016-11-18T09:25:14","guid":{"rendered":"https:\/\/www.italtel.com\/innovazione-e-responsabilita-sociale\/"},"modified":"2016-11-18T11:25:14","modified_gmt":"2016-11-18T09:25:14","slug":"innovazione-e-responsabilita-sociale","status":"publish","type":"post","link":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/","title":{"rendered":"Innovazione e responsabilit\u00e0 sociale"},"content":{"rendered":"<h5><strong>Innoviamo secondo i principi della CORPORATE SOCIAL REPONSIBILITY<\/strong><\/h5>\n<p>A Novembre 2016 \u00e8 stata riconfermata la \u201c<strong>Silver Recognition<\/strong>\u201d di EcoVadis.<\/p>\n<p>Italtel si sottopone annualmente alla valutazione della sua compliance ai principi della Corporate Social Responsibility.<\/p>\n<p>Italtel ha confermato la certificazione ricevuta nel 2015 da EcoVadis \u2013 organizzazione internazionale che ha sviluppato una piattaforma collaborativa per valutare la sostenibilit\u00e0 dei fornitori che operano nell\u2019ambito di supply chain globali.<\/p>\n<p>Molteplici sono le attivit\u00e0 e le iniziative di Italtel direttamente o indirettamente correlate con il miglioramento e l\u2019innovazione in ambito ambientale e sociale. Esse vanno dalla fase di concept, sviluppo, certificazione, deployment e manutenzione dei nostri prodotti e servizi proprietari, attraverso le attivit\u00e0 di ricerca proposte ed attuate a supporto (e in anticipazione) dei nostri prodotti e servizi, fino alle iniziative interne all\u2019azienda e alle nostre molteplici partecipazioni in Consorzi, Associazioni, Organismi Nazionali ed Internazionali.<\/p>\n<p>L\u2019impegno di Italtel per raggiungere i propri obiettivi di business viene condotto nel pieno rispetto dei diritti delle persone, della concorrenza leale, della salvaguardia dell\u2019ambiente, della tutela della salute e della sicurezza sul lavoro.<\/p>\n<p>Per saperne di pi\u00f9 leggi la pagina dedicata alla <a href=\"\/?page_id=7714\">Corporate Social Responibility<\/a> di Italtel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Innoviamo secondo i principi della CORPORATE SOCIAL REPONSIBILITY A Novembre 2016 \u00e8 stata riconfermata la \u201cSilver Recognition\u201d di EcoVadis. Italtel si sottopone annualmente alla valutazione della sua compliance ai principi&nbsp;&#8230;<\/p>\n","protected":false},"author":6,"featured_media":49403,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[734],"tags":[],"class_list":["post-55324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-annuncio-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Innovazione e responsabilit\u00e0 sociale - Italtel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innovazione e responsabilit\u00e0 sociale - Italtel\" \/>\n<meta property=\"og:description\" content=\"Innoviamo secondo i principi della CORPORATE SOCIAL REPONSIBILITY A Novembre 2016 \u00e8 stata riconfermata la \u201cSilver Recognition\u201d di EcoVadis. Italtel si sottopone annualmente alla valutazione della sua compliance ai principi&nbsp;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/\" \/>\n<meta property=\"og:site_name\" content=\"Italtel\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-18T09:25:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CSR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"826\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniela Fontana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Italtel\" \/>\n<meta name=\"twitter:site\" content=\"@Italtel\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela Fontana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/\"},\"author\":{\"name\":\"Daniela Fontana\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/person\\\/38f315d5a978255f0cf320055bad5afe\"},\"headline\":\"Innovazione e responsabilit\u00e0 sociale\",\"datePublished\":\"2016-11-18T09:25:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/\"},\"wordCount\":194,\"publisher\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/CSR.png\",\"articleSection\":[\"Annuncio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/\",\"name\":\"Innovazione e responsabilit\u00e0 sociale - Italtel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/CSR.png\",\"datePublished\":\"2016-11-18T09:25:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/CSR.png\",\"contentUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/CSR.png\",\"width\":826,\"height\":590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/innovazione-e-responsabilita-sociale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innovazione e responsabilit\u00e0 sociale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\",\"name\":\"Italtel\",\"description\":\"Italtel Group&#039;s company website\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\",\"name\":\"Italtel S.p.A.\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Italtel_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Italtel_logo.png\",\"width\":591,\"height\":139,\"caption\":\"Italtel S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Italtel\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/italtel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/italtel_hq\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/person\\\/38f315d5a978255f0cf320055bad5afe\",\"name\":\"Daniela Fontana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"caption\":\"Daniela Fontana\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Innovazione e responsabilit\u00e0 sociale - Italtel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/","og_locale":"it_IT","og_type":"article","og_title":"Innovazione e responsabilit\u00e0 sociale - Italtel","og_description":"Innoviamo secondo i principi della CORPORATE SOCIAL REPONSIBILITY A Novembre 2016 \u00e8 stata riconfermata la \u201cSilver Recognition\u201d di EcoVadis. Italtel si sottopone annualmente alla valutazione della sua compliance ai principi&nbsp;...","og_url":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/","og_site_name":"Italtel","article_published_time":"2016-11-18T09:25:14+00:00","og_image":[{"width":826,"height":590,"url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CSR.png","type":"image\/png"}],"author":"Daniela Fontana","twitter_card":"summary_large_image","twitter_creator":"@Italtel","twitter_site":"@Italtel","twitter_misc":{"Scritto da":"Daniela Fontana","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/#article","isPartOf":{"@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/"},"author":{"name":"Daniela Fontana","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/person\/38f315d5a978255f0cf320055bad5afe"},"headline":"Innovazione e responsabilit\u00e0 sociale","datePublished":"2016-11-18T09:25:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/"},"wordCount":194,"publisher":{"@id":"https:\/\/www.italtel.com\/de\/#organization"},"image":{"@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CSR.png","articleSection":["Annuncio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/","url":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/","name":"Innovazione e responsabilit\u00e0 sociale - Italtel","isPartOf":{"@id":"https:\/\/www.italtel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/#primaryimage"},"image":{"@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CSR.png","datePublished":"2016-11-18T09:25:14+00:00","breadcrumb":{"@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/#primaryimage","url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CSR.png","contentUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/01\/CSR.png","width":826,"height":590},{"@type":"BreadcrumbList","@id":"https:\/\/www.italtel.com\/it\/innovazione-e-responsabilita-sociale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italtel.com\/it\/"},{"@type":"ListItem","position":2,"name":"Innovazione e responsabilit\u00e0 sociale"}]},{"@type":"WebSite","@id":"https:\/\/www.italtel.com\/de\/#website","url":"https:\/\/www.italtel.com\/de\/","name":"Italtel","description":"Italtel Group&#039;s company website","publisher":{"@id":"https:\/\/www.italtel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italtel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.italtel.com\/de\/#organization","name":"Italtel S.p.A.","url":"https:\/\/www.italtel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/11\/Italtel_logo.png","contentUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/11\/Italtel_logo.png","width":591,"height":139,"caption":"Italtel S.p.A."},"image":{"@id":"https:\/\/www.italtel.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Italtel","https:\/\/www.linkedin.com\/company\/italtel\/","https:\/\/www.instagram.com\/italtel_hq\/"]},{"@type":"Person","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/person\/38f315d5a978255f0cf320055bad5afe","name":"Daniela Fontana","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","caption":"Daniela Fontana"}}]}},"_links":{"self":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts\/55324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/comments?post=55324"}],"version-history":[{"count":0,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts\/55324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/media\/49403"}],"wp:attachment":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/media?parent=55324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/categories?post=55324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/tags?post=55324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}