{"id":69665,"date":"2025-03-07T18:13:46","date_gmt":"2025-03-07T16:13:46","guid":{"rendered":"https:\/\/www.italtel.com\/celebrating-womens-voices-a-global-tribute-for-international-womens-day\/"},"modified":"2025-03-07T18:18:19","modified_gmt":"2025-03-07T16:18:19","slug":"celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna","status":"publish","type":"post","link":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/","title":{"rendered":"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna"},"content":{"rendered":"\n<div class=\"row\"  id=\"row-1313430804\">\n\n\n\t<div id=\"col-1552113283\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3252231276\" class=\"text fontsize_18 color_black\">\n\t\t\n\n<p data-start=\"113\" data-end=\"422\">In Italtel, la diversit\u00e0 non \u00e8 solo un valore in cui crediamo\u2014\u00e8 una forza che ci spinge avanti. Per celebrare la <strong data-start=\"226\" data-end=\"265\">Giornata Internazionale della Donna<\/strong>, abbiamo chiesto ai nostri colleghi in Italia, Spagna, Germania, Per\u00f9, Colombia e Brasile di condividere le loro riflessioni su cosa significa essere donna.<\/p>\n<p data-start=\"424\" data-end=\"690\">Il risultato \u00e8 un video emozionante che raccoglie le prospettive uniche, le emozioni e le esperienze delle donne che ogni giorno contribuiscono al futuro di Italtel. Le loro voci riflettono la passione, il talento e la determinazione che ci definiscono come azienda.<\/p>\n<p data-start=\"692\" data-end=\"935\">Crediamo che la diversit\u00e0 rafforzi la nostra comunit\u00e0, e siamo orgogliosi di dare spazio alle storie e alle parole delle nostre persone. Guarda il video e ascolta direttamente dai nostri colleghi le loro riflessioni sul potere di essere donna.<\/p>\n<p data-start=\"692\" data-end=\"935\"><strong data-start=\"940\" data-end=\"987\">Guarda il video ora e ascolta le loro voci.<\/strong><\/p>\n\t\t\t<\/div>\n\t\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><iframe loading=\"lazy\" title=\"Our voices for March 8th\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/yO_hpgLxTpY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1552113283 > .col-inner {\n  padding: 6rem 11rem 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-903988627\" class=\"col sibebar_col medium-3 small-12 large-3\"  >\n\t\t<div class=\"is-sticky-column\"><div class=\"is-sticky-column__inner\">\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-362533385\" class=\"text fontsize_16 color_black fontweight_500\">\n\t\t\n\nTECH KEYWORDS\n\t\t\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:2rem;margin-bottom:2rem;max-width:100%;height:1px;background-color:rgba(112, 112, 112, 0.302);\"><\/div>\n\n\t<div id=\"text-3671940964\" class=\"text fontsize_18 color_black\">\n\t\t\n\n<p>INTERNATIONAL WOMEN&#8217;S DAY<\/p>\n\t\t\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:2rem;margin-bottom:2rem;max-width:100%;height:1px;background-color:rgba(112, 112, 112, 0.302);\"><\/div>\n\n\t<div id=\"text-2865471400\" class=\"text fontsize_18 color_black\">\n\t\t\n\n<p>VOICES OF WOMEN<\/p>\n\t\t\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:2rem;margin-bottom:2rem;max-width:100%;height:1px;background-color:rgba(112, 112, 112, 0.302);\"><\/div>\n\n\t<div id=\"text-3244378983\" class=\"text fontsize_18 color_black\">\n\t\t\n\n<p>GENDER PARITY<\/p>\n\t\t\t<\/div>\n\t\n\t<div id=\"gap-274870164\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-274870164 {\n  padding-top: 13rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3314939850\" class=\"text fontsize_16 color_black fontweight_500\">\n\t\t\n\nSHARE THE PAGE\n\t\t\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:2rem;margin-bottom:2rem;max-width:100%;height:1px;background-color:rgba(112, 112, 112, 0.302);\"><\/div>\n\n\t<div class=\"img has-hover socialshare_icon linkedin x md-x lg-x y md-y lg-y\" id=\"image_1651876877\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/09\/Linkedin-icon.svg\" class=\"attachment-large size-large\" alt=\"Linkedin-icon\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1651876877 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover socialshare_icon instagram x md-x lg-x y md-y lg-y\" id=\"image_1611154600\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"27\" height=\"27\" src=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/07\/Raggruppa-12942.png\" class=\"attachment-large size-large\" alt=\"Instagram icon\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1611154600 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover socialshare_icon ex x md-x lg-x y md-y lg-y\" id=\"image_697642413\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/09\/X-icon.svg\" class=\"attachment-large size-large\" alt=\"X-icon\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_697642413 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\n<style>\n#col-903988627 > .is-sticky-column > .is-sticky-column__inner > .col-inner {\n  padding: 6rem 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":69659,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[378],"tags":[953,1026],"class_list":["post-69665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-it","tag-company-it","tag-women-in-tech-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna - Italtel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna - Italtel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/\" \/>\n<meta property=\"og:site_name\" content=\"Italtel\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T16:13:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T16:18:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png\" \/>\n\t<meta property=\"og:image:width\" content=\"755\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniela Fontana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Italtel\" \/>\n<meta name=\"twitter:site\" content=\"@Italtel\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela Fontana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/\"},\"author\":{\"name\":\"Daniela Fontana\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/person\\\/38f315d5a978255f0cf320055bad5afe\"},\"headline\":\"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna\",\"datePublished\":\"2025-03-07T16:13:46+00:00\",\"dateModified\":\"2025-03-07T16:18:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/\"},\"wordCount\":308,\"publisher\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vieo-International-Women-Day-Italtel.png\",\"keywords\":[\"Company\",\"Women in Tech\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/\",\"name\":\"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna - Italtel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vieo-International-Women-Day-Italtel.png\",\"datePublished\":\"2025-03-07T16:13:46+00:00\",\"dateModified\":\"2025-03-07T16:18:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vieo-International-Women-Day-Italtel.png\",\"contentUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Vieo-International-Women-Day-Italtel.png\",\"width\":755,\"height\":388,\"caption\":\"Vieo International Women Day Italtel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.italtel.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\",\"name\":\"Italtel\",\"description\":\"Italtel Group&#039;s company website\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#organization\",\"name\":\"Italtel S.p.A.\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Italtel_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.italtel.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Italtel_logo.png\",\"width\":591,\"height\":139,\"caption\":\"Italtel S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Italtel\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/italtel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/italtel_hq\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.italtel.com\\\/de\\\/#\\\/schema\\\/person\\\/38f315d5a978255f0cf320055bad5afe\",\"name\":\"Daniela Fontana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g\",\"caption\":\"Daniela Fontana\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna - Italtel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/","og_locale":"it_IT","og_type":"article","og_title":"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna - Italtel","og_url":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/","og_site_name":"Italtel","article_published_time":"2025-03-07T16:13:46+00:00","article_modified_time":"2025-03-07T16:18:19+00:00","og_image":[{"width":755,"height":388,"url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","type":"image\/png"}],"author":"Daniela Fontana","twitter_card":"summary_large_image","twitter_creator":"@Italtel","twitter_site":"@Italtel","twitter_misc":{"Scritto da":"Daniela Fontana","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/#article","isPartOf":{"@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/"},"author":{"name":"Daniela Fontana","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/person\/38f315d5a978255f0cf320055bad5afe"},"headline":"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna","datePublished":"2025-03-07T16:13:46+00:00","dateModified":"2025-03-07T16:18:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/"},"wordCount":308,"publisher":{"@id":"https:\/\/www.italtel.com\/de\/#organization"},"image":{"@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","keywords":["Company","Women in Tech"],"articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/","url":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/","name":"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna - Italtel","isPartOf":{"@id":"https:\/\/www.italtel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/#primaryimage"},"image":{"@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","datePublished":"2025-03-07T16:13:46+00:00","dateModified":"2025-03-07T16:18:19+00:00","breadcrumb":{"@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/#primaryimage","url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","contentUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2025\/03\/Vieo-International-Women-Day-Italtel.png","width":755,"height":388,"caption":"Vieo International Women Day Italtel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italtel.com\/it\/celebriamo-le-voci-delle-donne-un-tributo-globale-per-la-giornata-internazionale-della-donna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italtel.com\/it\/"},{"@type":"ListItem","position":2,"name":"Celebriamo le voci delle donne: un tributo globale per la Giornata Internazionale della Donna"}]},{"@type":"WebSite","@id":"https:\/\/www.italtel.com\/de\/#website","url":"https:\/\/www.italtel.com\/de\/","name":"Italtel","description":"Italtel Group&#039;s company website","publisher":{"@id":"https:\/\/www.italtel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italtel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.italtel.com\/de\/#organization","name":"Italtel S.p.A.","url":"https:\/\/www.italtel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/11\/Italtel_logo.png","contentUrl":"https:\/\/www.italtel.com\/wp-content\/uploads\/2024\/11\/Italtel_logo.png","width":591,"height":139,"caption":"Italtel S.p.A."},"image":{"@id":"https:\/\/www.italtel.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Italtel","https:\/\/www.linkedin.com\/company\/italtel\/","https:\/\/www.instagram.com\/italtel_hq\/"]},{"@type":"Person","@id":"https:\/\/www.italtel.com\/de\/#\/schema\/person\/38f315d5a978255f0cf320055bad5afe","name":"Daniela Fontana","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/834a03b0c73144a8ca36e17dc365b3fbadb34c9e44399b609a00f2231e694f6a?s=96&d=mm&r=g","caption":"Daniela Fontana"}}]}},"_links":{"self":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts\/69665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/comments?post=69665"}],"version-history":[{"count":2,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts\/69665\/revisions"}],"predecessor-version":[{"id":69667,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/posts\/69665\/revisions\/69667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/media\/69659"}],"wp:attachment":[{"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/media?parent=69665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/categories?post=69665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italtel.com\/it\/wp-json\/wp\/v2\/tags?post=69665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}